{"id":5168,"date":"2022-10-19T20:55:00","date_gmt":"2022-10-19T18:55:00","guid":{"rendered":"https:\/\/www.umweltaktivisten.de\/?p=5168"},"modified":"2022-10-27T11:29:58","modified_gmt":"2022-10-27T09:29:58","slug":"atomkraft-auf-dem-absteigenden-ast","status":"publish","type":"post","link":"https:\/\/www.umweltaktivisten.de\/index.php\/2022\/10\/19\/atomkraft-auf-dem-absteigenden-ast\/","title":{"rendered":"Atomkraft auf dem absteigenden Ast"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"333\" src=\"https:\/\/i0.wp.com\/www.umweltaktivisten.de\/wp-content\/uploads\/2020\/10\/Foto-Urantransport-1.jpg?resize=480%2C333&#038;ssl=1\" alt=\"\" class=\"wp-image-4529\" srcset=\"https:\/\/i0.wp.com\/www.umweltaktivisten.de\/wp-content\/uploads\/2020\/10\/Foto-Urantransport-1.jpg?w=480&amp;ssl=1 480w, https:\/\/i0.wp.com\/www.umweltaktivisten.de\/wp-content\/uploads\/2020\/10\/Foto-Urantransport-1.jpg?resize=300%2C208&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.umweltaktivisten.de\/wp-content\/uploads\/2020\/10\/Foto-Urantransport-1.jpg?resize=150%2C104&amp;ssl=1 150w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><figcaption>(Bild: BBU)<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Wer kennt nicht die Warnungen aus den Kreisen der Union, FDP und AfD, Deutschland gehe einen Sonderweg und werde weltweit nicht mehr ernst genommen, weil der Atomausstieg beschlossene Sache sei.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ein Blick in den<a href=\"https:\/\/www.worldnuclearreport.org\/IMG\/pdf\/wnisr2022-lr.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"> World N<\/a><a href=\"https:\/\/www.worldnuclearreport.org\/IMG\/pdf\/wnisr2022-lr.pdf\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">uclear Industry R<\/a><a href=\"https:\/\/www.worldnuclearreport.org\/IMG\/pdf\/wnisr2022-lr.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">eport<\/a> 2022, der vor Kurzem vorgelegt wurde, zeichnet ein v\u00f6llig anderes Bild. Es gibt nur 33 L\u00e4nder, in denen Atomkraftwerke betrieben werden und die Zahl der Reaktoren ist weiter im Sinkflug. Nach dem H\u00f6hepunkt 2018, in dem Jahr wurden weltweit 437 \u201ein operation\u201c gez\u00e4hlt, sank die Zahl der Reaktoren kontinuierlich, 2022, so listet der Report auf, waren es nur noch 411. Der weltweite Beitrag zur Stromerzeugung sank erstmalig unter 10 Prozent.<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201eEs lohnt, die Zahlen genauer zu betrachten,\u201c so die BI Umweltschutz L\u00fcchow-Dannenberg. Denn ohne die Reaktoren, die in China gebaut werden, sehe die Bilanz noch kruder aus. Zwischen 2002 und 2021 gab es 105 Reaktoren, die stillgelegt wurden gegen\u00fcber 98 Reaktoren, die neu ans Netz gingen, davon allein 50 in China. Dass es kaum Neubauten gibt, liege auf der Hand: \u201eDie Planungs- und Bauzeiten liegen zwischen 6 und 10 Jahren und die Kosten f\u00fcr einen Neubau explodierten.\u201c So konnte der Reaktor 3 des finnischen Atomkraftwerks Olkiluoto 13 Jahre versp\u00e4tet im September auf die volle Leistung von 1600 MW hochfahren, die Kosten waren von 3 auf 11 Milliarden Euro hochgeschnellt.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Der zweite Aspekt, der ins Auge f\u00e4llt, so BI-Sprecher Wolfgang Ehmke, ist die Tatsache, dass Russland den internationalen Markt beherrscht: 20 Reaktoren weltweit werden von der russischen Atomfirma Rosatom errichtet, darunter \u2013 trotz des Ukrainekrieges &#8211; auch in <a href=\"https:\/\/www.blaetter.de\/ausgabe\/2022\/juli\/wie-die-fliege-im-netz-europa-und-die-russische-atomindustrie\" target=\"_blank\" rel=\"noreferrer noopener\">Ungarn, d<\/a><a href=\"https:\/\/www.blaetter.de\/ausgabe\/2022\/juli\/wie-die-fliege-im-netz-europa-und-die-russische-atomindustrie\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">er S<\/a><a href=\"https:\/\/www.blaetter.de\/ausgabe\/2022\/juli\/wie-die-fliege-im-netz-europa-und-die-russische-atomindustrie\" target=\"_blank\" rel=\"noreferrer noopener\">lowakei und der T\u00fcrkei<\/a>. 18 europ\u00e4ische Atomkraftwerke sind auf Brennelementlieferungen aus Russland angewiesen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Report, so die BI, ist ein wertvoller Beitrag zur Versachlichung der Atomdebatte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quelle: <a href=\"https:\/\/www.bi-luechow-dannenberg.de\/2022\/10\/16\/atomkraft-auf-dem-absteigenden-ast\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Pressemitteilung <\/a>(BI L\u00fcchow-Dannenberg)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wer kennt nicht die Warnungen aus den Kreisen der Union, FDP und AfD, Deutschland gehe einen Sonderweg und werde weltweit nicht mehr ernst genommen, weil der Atomausstieg beschlossene Sache sei. Ein Blick in den World Nuclear Industry Report 2022, der vor Kurzem vorgelegt wurde, zeichnet ein v\u00f6llig anderes Bild. Es\u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/www.umweltaktivisten.de\/index.php\/2022\/10\/19\/atomkraft-auf-dem-absteigenden-ast\/\">weiter &#8230;<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":1,"featured_media":4531,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[21,1],"tags":[],"class_list":["post-5168","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atom","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atomkraft auf dem absteigenden Ast - umweltaktivisten.de<\/title>\n<meta name=\"robots\" content=\"index, nofollow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.umweltaktivisten.de\/index.php\/2022\/10\/19\/atomkraft-auf-dem-absteigenden-ast\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atomkraft auf dem absteigenden Ast - umweltaktivisten.de\" \/>\n<meta property=\"og:description\" content=\"Wer kennt nicht die Warnungen aus den Kreisen der Union, FDP und AfD, Deutschland gehe einen Sonderweg und werde weltweit nicht mehr ernst genommen, weil der Atomausstieg beschlossene Sache sei. Ein Blick in den World Nuclear Industry Report 2022, der vor Kurzem vorgelegt wurde, zeichnet ein v\u00f6llig anderes Bild. Es\u2026 weiter ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.umweltaktivisten.de\/index.php\/2022\/10\/19\/atomkraft-auf-dem-absteigenden-ast\/\" \/>\n<meta property=\"og:site_name\" content=\"umweltaktivisten.de\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-19T18:55:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-27T09:29:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.umweltaktivisten.de\/wp-content\/uploads\/2020\/10\/w_Foto-Urantransport-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"288\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marita\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"marita\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2022\\\/10\\\/19\\\/atomkraft-auf-dem-absteigenden-ast\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2022\\\/10\\\/19\\\/atomkraft-auf-dem-absteigenden-ast\\\/\"},\"author\":{\"name\":\"marita\",\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/#\\\/schema\\\/person\\\/af601319cc34a906612869cf3b4fd51a\"},\"headline\":\"Atomkraft auf dem absteigenden Ast\",\"datePublished\":\"2022-10-19T18:55:00+00:00\",\"dateModified\":\"2022-10-27T09:29:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2022\\\/10\\\/19\\\/atomkraft-auf-dem-absteigenden-ast\\\/\"},\"wordCount\":288,\"image\":{\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2022\\\/10\\\/19\\\/atomkraft-auf-dem-absteigenden-ast\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.umweltaktivisten.de\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/w_Foto-Urantransport-1.jpg?fit=288%2C200&ssl=1\",\"articleSection\":[\"Atom\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2022\\\/10\\\/19\\\/atomkraft-auf-dem-absteigenden-ast\\\/\",\"url\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2022\\\/10\\\/19\\\/atomkraft-auf-dem-absteigenden-ast\\\/\",\"name\":\"Atomkraft auf dem absteigenden Ast - umweltaktivisten.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2022\\\/10\\\/19\\\/atomkraft-auf-dem-absteigenden-ast\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2022\\\/10\\\/19\\\/atomkraft-auf-dem-absteigenden-ast\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.umweltaktivisten.de\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/w_Foto-Urantransport-1.jpg?fit=288%2C200&ssl=1\",\"datePublished\":\"2022-10-19T18:55:00+00:00\",\"dateModified\":\"2022-10-27T09:29:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/#\\\/schema\\\/person\\\/af601319cc34a906612869cf3b4fd51a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2022\\\/10\\\/19\\\/atomkraft-auf-dem-absteigenden-ast\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2022\\\/10\\\/19\\\/atomkraft-auf-dem-absteigenden-ast\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2022\\\/10\\\/19\\\/atomkraft-auf-dem-absteigenden-ast\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.umweltaktivisten.de\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/w_Foto-Urantransport-1.jpg?fit=288%2C200&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.umweltaktivisten.de\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/w_Foto-Urantransport-1.jpg?fit=288%2C200&ssl=1\",\"width\":288,\"height\":200,\"caption\":\"Bild: BBU\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2022\\\/10\\\/19\\\/atomkraft-auf-dem-absteigenden-ast\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atomkraft auf dem absteigenden Ast\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/#website\",\"url\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/\",\"name\":\"umweltaktivisten.de\",\"description\":\"&quot;Wir haben die Erde nur von unseren Kindern geborgt&quot;\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/#\\\/schema\\\/person\\\/af601319cc34a906612869cf3b4fd51a\",\"name\":\"marita\",\"url\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/author\\\/marita\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atomkraft auf dem absteigenden Ast - umweltaktivisten.de","robots":{"index":"index","follow":"nofollow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.umweltaktivisten.de\/index.php\/2022\/10\/19\/atomkraft-auf-dem-absteigenden-ast\/","og_locale":"de_DE","og_type":"article","og_title":"Atomkraft auf dem absteigenden Ast - umweltaktivisten.de","og_description":"Wer kennt nicht die Warnungen aus den Kreisen der Union, FDP und AfD, Deutschland gehe einen Sonderweg und werde weltweit nicht mehr ernst genommen, weil der Atomausstieg beschlossene Sache sei. Ein Blick in den World Nuclear Industry Report 2022, der vor Kurzem vorgelegt wurde, zeichnet ein v\u00f6llig anderes Bild. Es\u2026 weiter ...","og_url":"https:\/\/www.umweltaktivisten.de\/index.php\/2022\/10\/19\/atomkraft-auf-dem-absteigenden-ast\/","og_site_name":"umweltaktivisten.de","article_published_time":"2022-10-19T18:55:00+00:00","article_modified_time":"2022-10-27T09:29:58+00:00","og_image":[{"width":288,"height":200,"url":"https:\/\/www.umweltaktivisten.de\/wp-content\/uploads\/2020\/10\/w_Foto-Urantransport-1.jpg","type":"image\/jpeg"}],"author":"marita","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"marita","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.umweltaktivisten.de\/index.php\/2022\/10\/19\/atomkraft-auf-dem-absteigenden-ast\/#article","isPartOf":{"@id":"https:\/\/www.umweltaktivisten.de\/index.php\/2022\/10\/19\/atomkraft-auf-dem-absteigenden-ast\/"},"author":{"name":"marita","@id":"https:\/\/www.umweltaktivisten.de\/#\/schema\/person\/af601319cc34a906612869cf3b4fd51a"},"headline":"Atomkraft auf dem absteigenden Ast","datePublished":"2022-10-19T18:55:00+00:00","dateModified":"2022-10-27T09:29:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.umweltaktivisten.de\/index.php\/2022\/10\/19\/atomkraft-auf-dem-absteigenden-ast\/"},"wordCount":288,"image":{"@id":"https:\/\/www.umweltaktivisten.de\/index.php\/2022\/10\/19\/atomkraft-auf-dem-absteigenden-ast\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.umweltaktivisten.de\/wp-content\/uploads\/2020\/10\/w_Foto-Urantransport-1.jpg?fit=288%2C200&ssl=1","articleSection":["Atom"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.umweltaktivisten.de\/index.php\/2022\/10\/19\/atomkraft-auf-dem-absteigenden-ast\/","url":"https:\/\/www.umweltaktivisten.de\/index.php\/2022\/10\/19\/atomkraft-auf-dem-absteigenden-ast\/","name":"Atomkraft auf dem absteigenden Ast - umweltaktivisten.de","isPartOf":{"@id":"https:\/\/www.umweltaktivisten.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.umweltaktivisten.de\/index.php\/2022\/10\/19\/atomkraft-auf-dem-absteigenden-ast\/#primaryimage"},"image":{"@id":"https:\/\/www.umweltaktivisten.de\/index.php\/2022\/10\/19\/atomkraft-auf-dem-absteigenden-ast\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.umweltaktivisten.de\/wp-content\/uploads\/2020\/10\/w_Foto-Urantransport-1.jpg?fit=288%2C200&ssl=1","datePublished":"2022-10-19T18:55:00+00:00","dateModified":"2022-10-27T09:29:58+00:00","author":{"@id":"https:\/\/www.umweltaktivisten.de\/#\/schema\/person\/af601319cc34a906612869cf3b4fd51a"},"breadcrumb":{"@id":"https:\/\/www.umweltaktivisten.de\/index.php\/2022\/10\/19\/atomkraft-auf-dem-absteigenden-ast\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.umweltaktivisten.de\/index.php\/2022\/10\/19\/atomkraft-auf-dem-absteigenden-ast\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.umweltaktivisten.de\/index.php\/2022\/10\/19\/atomkraft-auf-dem-absteigenden-ast\/#primaryimage","url":"https:\/\/i0.wp.com\/www.umweltaktivisten.de\/wp-content\/uploads\/2020\/10\/w_Foto-Urantransport-1.jpg?fit=288%2C200&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.umweltaktivisten.de\/wp-content\/uploads\/2020\/10\/w_Foto-Urantransport-1.jpg?fit=288%2C200&ssl=1","width":288,"height":200,"caption":"Bild: BBU"},{"@type":"BreadcrumbList","@id":"https:\/\/www.umweltaktivisten.de\/index.php\/2022\/10\/19\/atomkraft-auf-dem-absteigenden-ast\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.umweltaktivisten.de\/"},{"@type":"ListItem","position":2,"name":"Atomkraft auf dem absteigenden Ast"}]},{"@type":"WebSite","@id":"https:\/\/www.umweltaktivisten.de\/#website","url":"https:\/\/www.umweltaktivisten.de\/","name":"umweltaktivisten.de","description":"&quot;Wir haben die Erde nur von unseren Kindern geborgt&quot;","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.umweltaktivisten.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.umweltaktivisten.de\/#\/schema\/person\/af601319cc34a906612869cf3b4fd51a","name":"marita","url":"https:\/\/www.umweltaktivisten.de\/author\/marita\/"}]}},"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/posts\/5168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/comments?post=5168"}],"version-history":[{"count":2,"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/posts\/5168\/revisions"}],"predecessor-version":[{"id":5170,"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/posts\/5168\/revisions\/5170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/media\/4531"}],"wp:attachment":[{"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/media?parent=5168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/categories?post=5168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/tags?post=5168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}