{"id":2991,"date":"2018-10-18T11:16:21","date_gmt":"2018-10-18T09:16:21","guid":{"rendered":"http:\/\/www.umweltaktivisten.de\/?p=2991"},"modified":"2018-10-18T11:18:34","modified_gmt":"2018-10-18T09:18:34","slug":"tagebau-hambach-tausende-werden-zu-blockaden-erwartet","status":"publish","type":"post","link":"https:\/\/www.umweltaktivisten.de\/index.php\/2018\/10\/18\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\/","title":{"rendered":"Tagebau Hambach: Tausende werden zu Blockaden erwartet"},"content":{"rendered":"<div class=\"post__excerpt\">\n<div id=\"attachment_2997\" style=\"width: 410px\" class=\"wp-caption aligncenter\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2997\" class=\"size-full wp-image-2997\" src=\"https:\/\/i0.wp.com\/www.umweltaktivisten.de\/wp-content\/uploads\/2018\/10\/Ende-Gelaende_DE400x300.jpg?resize=400%2C300&#038;ssl=1\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/www.umweltaktivisten.de\/wp-content\/uploads\/2018\/10\/Ende-Gelaende_DE400x300.jpg?w=400&amp;ssl=1 400w, https:\/\/i0.wp.com\/www.umweltaktivisten.de\/wp-content\/uploads\/2018\/10\/Ende-Gelaende_DE400x300.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.umweltaktivisten.de\/wp-content\/uploads\/2018\/10\/Ende-Gelaende_DE400x300.jpg?resize=150%2C113&amp;ssl=1 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><p id=\"caption-attachment-2997\" class=\"wp-caption-text\">Foto: Ende Gel\u00e4nde<\/p><\/div>\n<h5>Tausende zu Braunkohle-Blockaden am Tagebau Hambach erwartet (25.-29.10) + \u00d6ffentliches Aktionstraining und Presse-Briefing am 26.10.2018 + Sonderzug aus Prag<\/h5>\n<\/div>\n<div class=\"post__content richtext\">\n<p><strong>Am letzten Oktober-Wochenende werden tausende Aktivist*innen die Kohle-Infrastruktur rund um den Tagebau Hambach blockieren. Ende Gel\u00e4nde fordert mit der Aktion den sofortigen Kohleausstieg und Klimagerechtigkeit weltweit.<\/strong><\/p>\n<p>\u201eDer vorl\u00e4ufige Rodungs-Stopp f\u00fcr den Hambacher Wald ist ein grandioser Erfolg. Doch die Kohle-Bagger bedrohen weiterhin D\u00f6rfer, Natur und das globale Klima. Die Wissenschaft r\u00e4t dringend zu einem sofortigen Kohleausstieg, doch die Kohlekommission steht beim Klimaschutz auf der Bremse. Darum wird Ende Gel\u00e4nde den Kohleausstieg mit zivilem Ungehorsam selbst einleiten\u201c, so Karolina Drzewo, Pressesprecherin von Ende Gel\u00e4nde.<\/p>\n<p><a name=\"move400743370\"><\/a>Gerne m\u00f6chten wir Ihnen die M\u00f6glichkeit bieten, im Vorfeld und w\u00e4hrend der Aktion \u00fcber die Proteste von Ende Gel\u00e4nde zu berichten. Hierf\u00fcr stehen wir Ihnen f\u00fcr Interviews zur Verf\u00fcgung. Es gibt die M\u00f6glichkeit, Aktivist*innen in die Aktion zu begleiten oder Portr\u00e4ts \u00fcber Aktivist*innen zu schreiben und zu filmen.<\/p>\n<p>Am <strong>Freitag, den 26.10.<\/strong>, <strong>um 11.30 Uhr<\/strong> bieten wir Ihnen ein <strong>\u00f6ffentliches Aktionstraining<\/strong> an, bei dem Sie filmen und fotografieren k\u00f6nnen. Im Anschluss daran, <strong>um 12.15 Uhr<\/strong>, findet ein <strong>Presse-Briefing<\/strong> statt, zu dem wir Sie insbesondere einladen, wenn Sie Aktivist*innen begleiten m\u00f6chten. \u00dcber die genauen Treffpunkte f\u00fcr diese Termine werden wir Sie kurzfristig informieren.<\/p>\n<p>Dieses Jahr wird es einen Ende Gel\u00e4nde Sonderzug geben, der am <strong>25.10. nachmittags in Prag<\/strong> startet und \u00fcber <b>Leipzig<\/b>, <b>Berlin<\/b> und <b>Hannover<\/b> direkt ins Rheinische Braunkohlerevier nach D\u00fcren f\u00e4hrt. Pressevertreter*innen sind herzlich eingeladen, im Zug mitzufahren und schon dort mit Aktivist*innen zu sprechen. Daf\u00fcr bitten wir um fr\u00fchzeitige Anmeldung.<\/p>\n<p>Bereits am 6. Oktober 2018 hat Ende Gel\u00e4nde sich an Protesten f\u00fcr die Rettung des Hambacher Waldes und f\u00fcr den sofortigen Kohleausstieg beteiligt. Den Pressespiegel zu den Aktionen finden Sie <a href=\"https:\/\/www.ende-gelaende.org\/de\/press-release\/presseeinladung-vom-12-10-2018\/\" target=\"_blank\" rel=\"noopener\">hier<\/a>, Fotos auf <a href=\"https:\/\/www.flickr.com\/photos\/133937251@N05\/\" target=\"_blank\" rel=\"noopener\">flickr<\/a>.<\/p>\n<p>(Pressemitteilung: Ende Gel\u00e4nde)<\/p>\n<p>twitter: <a href=\"https:\/\/twitter.com\/Ende__Gelaende\" target=\"_blank\" rel=\"noopener\">@Ende_Gelaende<\/a><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/player.vimeo.com\/video\/289392434?app_id=122963\" width=\"900\" height=\"506\" frameborder=\"0\" title=\"ENDE GEL&Auml;NDE 25.-29. Oktober im Rheinland\" allow=\"autoplay; fullscreen\" allowfullscreen><\/iframe><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tausende zu Braunkohle-Blockaden am Tagebau Hambach erwartet (25.-29.10) + \u00d6ffentliches Aktionstraining und Presse-Briefing am 26.10.2018 + Sonderzug aus Prag Am letzten Oktober-Wochenende werden tausende Aktivist*innen die Kohle-Infrastruktur rund um den Tagebau Hambach blockieren. Ende Gel\u00e4nde fordert mit der Aktion den sofortigen Kohleausstieg und Klimagerechtigkeit weltweit. \u201eDer vorl\u00e4ufige Rodungs-Stopp f\u00fcr den\u2026<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/www.umweltaktivisten.de\/index.php\/2018\/10\/18\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\/\">weiter &#8230;<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":1,"featured_media":2999,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1,20],"tags":[],"class_list":["post-2991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-braunkohle"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tagebau Hambach: Tausende werden zu Blockaden erwartet - umweltaktivisten.de<\/title>\n<meta name=\"description\" content=\"Tausende zu Braunkohle-Blockaden am Tagebau Hambach erwartet (25.-29.10.) \u00d6ffentliches Aktionstraining und Presse-Briefing am 26.10.2018 Sonderzug aus Prag\" \/>\n<meta name=\"robots\" content=\"index, nofollow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.umweltaktivisten.de\/index.php\/2018\/10\/18\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tagebau Hambach: Tausende werden zu Blockaden erwartet - umweltaktivisten.de\" \/>\n<meta property=\"og:description\" content=\"Tausende zu Braunkohle-Blockaden am Tagebau Hambach erwartet (25.-29.10.) \u00d6ffentliches Aktionstraining und Presse-Briefing am 26.10.2018 Sonderzug aus Prag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.umweltaktivisten.de\/index.php\/2018\/10\/18\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\/\" \/>\n<meta property=\"og:site_name\" content=\"umweltaktivisten.de\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-18T09:16:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-18T09:18:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.umweltaktivisten.de\/wp-content\/uploads\/2018\/10\/w_Ende-Gelaende_DE300x200.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"267\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marita\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"marita\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2018\\\/10\\\/18\\\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2018\\\/10\\\/18\\\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\\\/\"},\"author\":{\"name\":\"marita\",\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/#\\\/schema\\\/person\\\/af601319cc34a906612869cf3b4fd51a\"},\"headline\":\"Tagebau Hambach: Tausende werden zu Blockaden erwartet\",\"datePublished\":\"2018-10-18T09:16:21+00:00\",\"dateModified\":\"2018-10-18T09:18:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2018\\\/10\\\/18\\\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\\\/\"},\"wordCount\":339,\"image\":{\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2018\\\/10\\\/18\\\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.umweltaktivisten.de\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/w_Ende-Gelaende_DE300x200.jpg?fit=267%2C200&ssl=1\",\"articleSection\":{\"1\":\"Braunkohle\"},\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2018\\\/10\\\/18\\\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\\\/\",\"url\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2018\\\/10\\\/18\\\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\\\/\",\"name\":\"Tagebau Hambach: Tausende werden zu Blockaden erwartet - umweltaktivisten.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2018\\\/10\\\/18\\\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2018\\\/10\\\/18\\\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.umweltaktivisten.de\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/w_Ende-Gelaende_DE300x200.jpg?fit=267%2C200&ssl=1\",\"datePublished\":\"2018-10-18T09:16:21+00:00\",\"dateModified\":\"2018-10-18T09:18:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/#\\\/schema\\\/person\\\/af601319cc34a906612869cf3b4fd51a\"},\"description\":\"Tausende zu Braunkohle-Blockaden am Tagebau Hambach erwartet (25.-29.10.) \u00d6ffentliches Aktionstraining und Presse-Briefing am 26.10.2018 Sonderzug aus Prag\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2018\\\/10\\\/18\\\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2018\\\/10\\\/18\\\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2018\\\/10\\\/18\\\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.umweltaktivisten.de\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/w_Ende-Gelaende_DE300x200.jpg?fit=267%2C200&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.umweltaktivisten.de\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/w_Ende-Gelaende_DE300x200.jpg?fit=267%2C200&ssl=1\",\"width\":267,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/index.php\\\/2018\\\/10\\\/18\\\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tagebau Hambach: Tausende werden zu Blockaden erwartet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/#website\",\"url\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/\",\"name\":\"umweltaktivisten.de\",\"description\":\"&quot;Wir haben die Erde nur von unseren Kindern geborgt&quot;\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/#\\\/schema\\\/person\\\/af601319cc34a906612869cf3b4fd51a\",\"name\":\"marita\",\"url\":\"https:\\\/\\\/www.umweltaktivisten.de\\\/author\\\/marita\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tagebau Hambach: Tausende werden zu Blockaden erwartet - umweltaktivisten.de","description":"Tausende zu Braunkohle-Blockaden am Tagebau Hambach erwartet (25.-29.10.) \u00d6ffentliches Aktionstraining und Presse-Briefing am 26.10.2018 Sonderzug aus Prag","robots":{"index":"index","follow":"nofollow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.umweltaktivisten.de\/index.php\/2018\/10\/18\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\/","og_locale":"de_DE","og_type":"article","og_title":"Tagebau Hambach: Tausende werden zu Blockaden erwartet - umweltaktivisten.de","og_description":"Tausende zu Braunkohle-Blockaden am Tagebau Hambach erwartet (25.-29.10.) \u00d6ffentliches Aktionstraining und Presse-Briefing am 26.10.2018 Sonderzug aus Prag","og_url":"https:\/\/www.umweltaktivisten.de\/index.php\/2018\/10\/18\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\/","og_site_name":"umweltaktivisten.de","article_published_time":"2018-10-18T09:16:21+00:00","article_modified_time":"2018-10-18T09:18:34+00:00","og_image":[{"width":267,"height":200,"url":"https:\/\/www.umweltaktivisten.de\/wp-content\/uploads\/2018\/10\/w_Ende-Gelaende_DE300x200.jpg","type":"image\/jpeg"}],"author":"marita","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"marita","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.umweltaktivisten.de\/index.php\/2018\/10\/18\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\/#article","isPartOf":{"@id":"https:\/\/www.umweltaktivisten.de\/index.php\/2018\/10\/18\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\/"},"author":{"name":"marita","@id":"https:\/\/www.umweltaktivisten.de\/#\/schema\/person\/af601319cc34a906612869cf3b4fd51a"},"headline":"Tagebau Hambach: Tausende werden zu Blockaden erwartet","datePublished":"2018-10-18T09:16:21+00:00","dateModified":"2018-10-18T09:18:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.umweltaktivisten.de\/index.php\/2018\/10\/18\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\/"},"wordCount":339,"image":{"@id":"https:\/\/www.umweltaktivisten.de\/index.php\/2018\/10\/18\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.umweltaktivisten.de\/wp-content\/uploads\/2018\/10\/w_Ende-Gelaende_DE300x200.jpg?fit=267%2C200&ssl=1","articleSection":{"1":"Braunkohle"},"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.umweltaktivisten.de\/index.php\/2018\/10\/18\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\/","url":"https:\/\/www.umweltaktivisten.de\/index.php\/2018\/10\/18\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\/","name":"Tagebau Hambach: Tausende werden zu Blockaden erwartet - umweltaktivisten.de","isPartOf":{"@id":"https:\/\/www.umweltaktivisten.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.umweltaktivisten.de\/index.php\/2018\/10\/18\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\/#primaryimage"},"image":{"@id":"https:\/\/www.umweltaktivisten.de\/index.php\/2018\/10\/18\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.umweltaktivisten.de\/wp-content\/uploads\/2018\/10\/w_Ende-Gelaende_DE300x200.jpg?fit=267%2C200&ssl=1","datePublished":"2018-10-18T09:16:21+00:00","dateModified":"2018-10-18T09:18:34+00:00","author":{"@id":"https:\/\/www.umweltaktivisten.de\/#\/schema\/person\/af601319cc34a906612869cf3b4fd51a"},"description":"Tausende zu Braunkohle-Blockaden am Tagebau Hambach erwartet (25.-29.10.) \u00d6ffentliches Aktionstraining und Presse-Briefing am 26.10.2018 Sonderzug aus Prag","breadcrumb":{"@id":"https:\/\/www.umweltaktivisten.de\/index.php\/2018\/10\/18\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.umweltaktivisten.de\/index.php\/2018\/10\/18\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.umweltaktivisten.de\/index.php\/2018\/10\/18\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\/#primaryimage","url":"https:\/\/i0.wp.com\/www.umweltaktivisten.de\/wp-content\/uploads\/2018\/10\/w_Ende-Gelaende_DE300x200.jpg?fit=267%2C200&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.umweltaktivisten.de\/wp-content\/uploads\/2018\/10\/w_Ende-Gelaende_DE300x200.jpg?fit=267%2C200&ssl=1","width":267,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.umweltaktivisten.de\/index.php\/2018\/10\/18\/tagebau-hambach-tausende-werden-zu-blockaden-erwartet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.umweltaktivisten.de\/"},{"@type":"ListItem","position":2,"name":"Tagebau Hambach: Tausende werden zu Blockaden erwartet"}]},{"@type":"WebSite","@id":"https:\/\/www.umweltaktivisten.de\/#website","url":"https:\/\/www.umweltaktivisten.de\/","name":"umweltaktivisten.de","description":"&quot;Wir haben die Erde nur von unseren Kindern geborgt&quot;","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.umweltaktivisten.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.umweltaktivisten.de\/#\/schema\/person\/af601319cc34a906612869cf3b4fd51a","name":"marita","url":"https:\/\/www.umweltaktivisten.de\/author\/marita\/"}]}},"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/posts\/2991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/comments?post=2991"}],"version-history":[{"count":7,"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/posts\/2991\/revisions"}],"predecessor-version":[{"id":3001,"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/posts\/2991\/revisions\/3001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/media\/2999"}],"wp:attachment":[{"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/media?parent=2991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/categories?post=2991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.umweltaktivisten.de\/index.php\/wp-json\/wp\/v2\/tags?post=2991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}